{"id":1453,"date":"2020-09-10T15:19:45","date_gmt":"2020-09-10T20:19:45","guid":{"rendered":"http:\/\/einsteresante.com\/?p=1453"},"modified":"2020-09-10T15:19:47","modified_gmt":"2020-09-10T20:19:47","slug":"como-unir-puentes-entre-la-politica-y-la-ciencia-para-afrontar-el-covid-19","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2020\/09\/10\/como-unir-puentes-entre-la-politica-y-la-ciencia-para-afrontar-el-covid-19\/","title":{"rendered":"\u00bfC\u00f3mo unir puentes entre la pol\u00edtica y la ciencia para afrontar el COVID-19?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En mayo la epidemi\u00f3loga Caitlin Rivers dio un giro a las \u00f3rdenes de confinamiento. Hab\u00eda sido llamada para testificar ante el Congreso de los Estados Unidos y estaba intimidada. &#8220;Est\u00e1s mirando el estrado y viendo a todas estas personas eminentes. Es una experiencia realmente poderosa&#8221;, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, empezaron a llegar las preguntas sobre la respuesta estadounidense al virus, Rivers estaba en su terreno. Cinco a\u00f1os despu\u00e9s de salir de la escuela de posgrado, tiene experiencia en hablarle a los pol\u00edticos sobre la ciencia detr\u00e1s de una pandemia, ha desarrollado modelos para predecir la expansi\u00f3n del S\u00edndrome Respiratorio Agudo de Oriente Medio (MERS) y el \u00e9bola e inform\u00f3 al Departamento de Defensa de Estados Unidos (DOD) sobre c\u00f3mo deb\u00edan ser las respuestas al brote. Ahora est\u00e1 trabajando en el Centro John Hopkins para la Seguridad Sanitaria, un think tank que les da informaci\u00f3n a los l\u00edderes internacionales para que estos puedan responder de forma efectiva a epidemias y desastres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencias, charlas privadas con legisladores y oficiales locales, as\u00ed como en redes sociales, Rivers se ha ganado la reputaci\u00f3n de ser una narradora concisa y con tacto de la pandemia. &#8220;Uno de mis objetivos&#8221;, dice, &#8220;es mantener la energ\u00eda, la intenci\u00f3n, en torno a la pregunta m\u00e1s importante:&#8221; \u00bfVamos en la direcci\u00f3n correcta?&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rivers se interes\u00f3 en la epidemiolog\u00eda cuando era estudiante de pregrado en la Universidad de New Hampshire, inspirada en parte por el libro <em>Monta\u00f1as m\u00e1s all\u00e1 de las monta\u00f1as: la b\u00fasqueda del Dr. Paul Farmer, un hombre que curar\u00eda el mundo<\/em> escrito por Tracy Kidder y en el que describe los esfuerzos de m\u00e9dicos antrop\u00f3logos para erradicar enfermedades en pa\u00edses en v\u00edas de desarrollo. Rivers admir\u00f3 &#8220;el respeto que trajo a las poblaciones con las que estaba trabajando&#8221;, dice, &#8220;y solo la visi\u00f3n: no estaba dispuesto a permitir que nada lo detuviera&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rivers se especializ\u00f3 en antropolog\u00eda y difunde &#8220;la comprensi\u00f3n del antrop\u00f3logo de c\u00f3mo lo que parecen ser culturas totalmente diferentes pueden comunicarse entre s\u00ed: el mundo de las pol\u00edticas y los epidemi\u00f3logos que modelan&#8221; dice Stephen Eubank, modelador epidemiol\u00f3gico de la Universidad de Virginia (UVA) y quien fue tutor de Rivers durante su posgrado en epidemiolog\u00eda y enfermedades infecciosas en el Instituto Polit\u00e9cnico y Universidad Estatal de Virginia (Virginia Tech).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su Ph.D coincidi\u00f3 con el brote de \u00e9bola en \u00c1frica Occidental, y en el laboratorio del epidemi\u00f3logo de Virginia Tech Brian Lewis ayud\u00f3 a preparar los informes semanales para los expertos del DOD \u201cCaitlin sol\u00eda enviarme correos electr\u00f3nicos como a las tres de la ma\u00f1ana: &#8216;\u00a1Actualic\u00e9 esto para incluir esta cosita! \u00a1Puede poner esto en la diapositiva 12! \u201d, Recuerda Lewis, ahora tambi\u00e9n en la UVA. Las demandas de una epidemia &#8220;se adaptan bien a mi personalidad&#8221;, dice Rivers. &#8220;No me importa trabajar duro y me gusta tener un prop\u00f3sito&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras se sentaba ante un subcomit\u00e9 de asignaciones en la C\u00e1mara de Representantes en mayo, el pa\u00eds hab\u00eda avanzado. Las \u00f3rdenes de quedarse en casa estaban empezando a mantener a raya nuevos casos de COVID-19. Pero la naci\u00f3n estaba al borde de una reapertura generalizada que pondr\u00eda en riesgo los logros obtenidos con tanto esfuerzo. \u201cEstamos en un momento cr\u00edtico de esta lucha\u201d, dijo a los representantes, advirtiendo que un plan nacional claro para pruebas, rastreo de contactos y fortalecimiento de los sistemas de salud era esencial para prevenir decenas de miles de muertes m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ya en marzo, Rivers, el excomisionado de la Administraci\u00f3n de Alimentos y Medicamentos, Scott Gottlieb, y sus colegas del American Enterprise Institute hab\u00edan establecido criterios para reabrir negocios de manera segura, incluida la espera de una reducci\u00f3n sostenida de casos. En su testimonio ante el Congreso de mayo, inst\u00f3 al gobierno federal a desarrollar un plan nacional para eliminar la escasez de pruebas y anticipar cuellos de botella en el suministro de reactivos y materiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las cosas podr\u00edan haber ido de otra manera si m\u00e1s personas en posiciones de poder hubieran seguido el consejo de Rivers. Cuatro meses despu\u00e9s, Estados Unidos todav\u00eda registra decenas de miles de casos nuevos por d\u00eda y representa aproximadamente una quinta parte de las muertes por COVID-19 documentadas en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas cosas no se desarrollaron como me hubiera gustado, ciertamente\u201d, dice Rivers sobre la reapertura de Estados Unidos. \u201cLa pol\u00edtica puede volverse tan frustrante porque se siente, no necesariamente como un asesor, sino como un ciudadano, como, &#8216;\u00bfPor qu\u00e9 no puedes verlo como yo lo veo?&#8217;\u201d. Pero, agrega, simpatiza con las presiones que los tomadores de decisiones locales sintieron para restaurar sus econom\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eubank dice que echar la culpa y provocar controversias no es productivo para alguien ansioso por influir en la pol\u00edtica, citando la aversi\u00f3n del director del Instituto Nacional de Alergias y Enfermedades Infecciosas, Anthony Fauci, a discutir p\u00fablicamente su relaci\u00f3n con la administraci\u00f3n Trump. Por supuesto, a\u00f1ade Eubank, Fauci tiene d\u00e9cadas de experiencia enhebrando esta aguja. Pero Rivers tambi\u00e9n lo entiende y se est\u00e1 defendiendo a los pocos a\u00f1os de graduarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo profesorado junior, no tenemos a nadie ayudando. No tenemos personal \u201d, dice Natalie Dean, bioestad\u00edstica de la Universidad de Florida que es coautora de editoriales con Rivers sobre c\u00f3mo interpretar los estudios de anticuerpos y la necesidad de datos epidemiol\u00f3gicos m\u00e1s detallados y transparentes. &#8220;Creo que ambos nos estamos adaptando a que tanta gente nos pregunte cosas&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No son solo los pol\u00edticos los que est\u00e1n recurriendo a Rivers en busca de claridad sobre la pandemia. En Twitter, que antes usaba principalmente para discutir nuevos resultados con sus colegas, se ha convertido en un arte al ofrecer una visi\u00f3n general de 280 caracteres a sus seguidores, que ahora suman m\u00e1s de 140.000.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Al principio de un brote, a menudo encontramos solo los casos m\u00e1s graves&#8221;, tuite\u00f3 en febrero. \u201cParece que la gente est\u00e1 bastante enferma, lo cual da miedo. Es una especie de ilusi\u00f3n &#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando algunas regiones dieron la vuelta a la esquina en abril, predijo \u201cuna creciente agitaci\u00f3n sobre si es necesario quedarse en casa. No se equivoque, es y fue &#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No debemos entumecernos&#8221;, inst\u00f3 en julio cuando Estados Unidos superaba las 150.000 muertes. &#8220;Esos n\u00fameros representan personas, personas que fueron amadas&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los lectores gravitan hacia estos res\u00famenes sensatos incluso cuando las noticias son malas, dice Dean, quien describe a Rivers como su &#8220;amiga de la pandemia&#8221;. Su amistad naci\u00f3 en Twitter, dice ella, donde se conectaron sobre la lucha de cuidar a los ni\u00f1os peque\u00f1os mientras trabajaban desde casa. (Rivers tiene gemelos de 19 meses y un ni\u00f1o de 6 a\u00f1os).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rivers admite que las demandas de la pandemia han sido &#8220;mucho para manejar&#8221;, pero tambi\u00e9n ve oportunidades, incluida la posibilidad de revivir una propuesta que preparar\u00eda mejor al pa\u00eds para la pr\u00f3xima amenaza viral. Mientras estaba en la escuela de posgrado, Rivers y sus colegas propusieron crear un Centro Nacional de Pron\u00f3stico de Enfermedades Infecciosas, similar al Servicio Meteorol\u00f3gico Nacional, que pondr\u00eda un equipo coordinado de expertos en modelos de epidemias dentro del gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, los expertos acad\u00e9micos ofrecen en gran medida su tiempo como voluntarios. \u201cNo hay otra capacidad de importancia estrat\u00e9gica nacional que manejemos as\u00ed\u201d, dice. \u201cNo dejamos que los militares se autoorganicen. No permitimos que el centro nacional de huracanes sean acad\u00e9micos en varias universidades que se ofrecen como voluntarios &#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2015, la propuesta parec\u00eda tener una oportunidad. Rivers, con colegas que inclu\u00edan al asesor de biodefensa Dylan George, entonces en la Oficina de Pol\u00edtica Cient\u00edfica y Tecnol\u00f3gica de la Casa Blanca, discutieron la idea en una reuni\u00f3n de la Casa Blanca sobre preparaci\u00f3n para epidemias. Pero nunca avanz\u00f3 a una iniciativa formal o una l\u00ednea en el presupuesto federal. \u201cLlegamos al ciclo presupuestario en el momento equivocado\u201d, dice George, quien ahora trabaja en la firma de inversi\u00f3n en seguridad nacional In-Q-Tel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El COVID-19 ha dado un nuevo impulso al esfuerzo. Rivers dice que se ha estado reuniendo con el personal del Congreso al respecto, y tiene la esperanza de que los esfuerzos pasados sentaron las bases a pesar de que no dieron sus frutos a tiempo para ayudar con COVID-19. Ella desear\u00eda que la iniciativa se hubiera lanzado en 2015, dice, &#8220;pero el segundo mejor momento es ahora&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.sciencemag.org\/news\/2020\/09\/fight-covid-19-young-epidemiologist-bridges-gulf-between-science-and-us-politics\">Science<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mayo la epidemi\u00f3loga Caitlin Rivers dio un giro a las \u00f3rdenes de confinamiento. Hab\u00eda sido llamada para testificar ante el Congreso de los Estados Unidos y estaba intimidada. &#8220;Est\u00e1s mirando el estrado y viendo a todas estas personas eminentes. Es una experiencia realmente poderosa&#8221;, dice. Entonces, empezaron a llegar las preguntas sobre la respuesta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-1453","post","type-post","status-publish","format-standard","hentry","category-politica-y-sociedad"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/1453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=1453"}],"version-history":[{"count":5,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/1453\/revisions"}],"predecessor-version":[{"id":1459,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/1453\/revisions\/1459"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=1453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=1453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=1453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}