{"id":20378,"date":"2022-04-29T04:58:40","date_gmt":"2022-04-29T09:58:40","guid":{"rendered":"https:\/\/einsteresante.com\/?p=20378"},"modified":"2022-04-29T04:58:42","modified_gmt":"2022-04-29T09:58:42","slug":"cual-es-la-temperatura-mas-alta-del-universo-conocido-podemos-alcanzarla","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2022\/04\/29\/cual-es-la-temperatura-mas-alta-del-universo-conocido-podemos-alcanzarla\/","title":{"rendered":"\u00bfCu\u00e1l es la temperatura m\u00e1s alta del universo conocido? \u00bfPodemos alcanzarla?"},"content":{"rendered":"\n<p>Por lo que sabemos sobre nuestro Universo, la temperatura m\u00e1s fr\u00eda posible es cero grados Kelvin &#8216;absolutos&#8217;, o -273,15 \u00b0C. Pero, \u00bfqu\u00e9 pasa con la temperatura m\u00e1s alta posible?<\/p>\n\n\n\n<p>La f\u00edsica es un poco confusa sobre c\u00f3mo se ve el m\u00e1s caliente de los calientes, pero te\u00f3ricamente hablando, tal cosa existe, o al menos existi\u00f3, una vez. Se llama la temperatura de Planck, pero, como todo en la vida, tampoco es tan simple.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es la temperatura, de todos modos?<br><\/strong>Lo primero que podr\u00eda venir a la mente al pensar en la temperatura podr\u00eda ser una descripci\u00f3n de la cantidad de calor que contiene un objeto. O, para el caso, no contiene.<\/p>\n\n\n\n<p>El calor, o energ\u00eda t\u00e9rmica, es una parte importante de la explicaci\u00f3n. Nuestra comprensi\u00f3n intuitiva del calor es que fluye de fuentes con temperaturas m\u00e1s altas a aquellas con temperaturas m\u00e1s bajas, como una taza de t\u00e9 humeante que se enfr\u00eda mientras la soplamos.<\/p>\n\n\n\n<p>En t\u00e9rminos f\u00edsicos, la energ\u00eda t\u00e9rmica se parece m\u00e1s a un promedio de movimientos aleatorios en un sistema, generalmente entre part\u00edculas como \u00e1tomos y mol\u00e9culas. Coloca dos objetos con cantidades variables de energ\u00eda t\u00e9rmica lo suficientemente cerca como para tocarlos, y los movimientos aleatorios se combinar\u00e1n hasta que ambos objetos est\u00e9n en equilibrio. Como forma de energ\u00eda, el calor se mide en unidades de joules.<\/p>\n\n\n\n<p>La temperatura, por otro lado, describe la transferencia de energ\u00eda de las regiones m\u00e1s calientes a las m\u00e1s fr\u00edas, al menos te\u00f3ricamente. Por lo general, se describe como una escala, en unidades como Kelvin, Celsius o Fahrenheit. La llama de una vela puede tener una temperatura alta en comparaci\u00f3n con un iceberg, pero la cantidad de energ\u00eda t\u00e9rmica en su mecha calentada no har\u00e1 mucha diferencia cuando se coloca contra la monta\u00f1a de agua congelada.<\/p>\n\n\n\n<p><strong>Entonces, \u00bfqu\u00e9 es exactamente el cero absoluto?<br><\/strong>El cero absoluto es una temperatura, por lo que es una medida de la transferencia relativa de energ\u00eda t\u00e9rmica. En teor\u00eda, marca un punto en una escala de temperatura en el que no se puede eliminar m\u00e1s energ\u00eda t\u00e9rmica de un sistema, gracias a las leyes de la termodin\u00e1mica.<\/p>\n\n\n\n<p>En t\u00e9rminos pr\u00e1cticos, este punto preciso est\u00e1 siempre fuera de alcance. Pero podemos acercarnos tentadoramente: todo lo que necesitamos son formas de disminuir la cantidad promedio de energ\u00eda t\u00e9rmica distribuida entre las part\u00edculas de un sistema, tal vez con la ayuda de l\u00e1seres o el tipo correcto de campo magn\u00e9tico giratorio. Pero al final, siempre hay un promedio de energ\u00eda que dejar\u00e1 la temperatura una fracci\u00f3n por encima del l\u00edmite te\u00f3rico de lo que se puede extraer.<\/p>\n\n\n\n<p><strong>\u00bfCu\u00e1l es la temperatura m\u00e1s alta posible?<br><\/strong>Si el cero absoluto establece un l\u00edmite para extraer energ\u00eda t\u00e9rmica de un sistema, podr\u00eda ser l\u00f3gico que tambi\u00e9n haya un l\u00edmite para la cantidad de energ\u00eda t\u00e9rmica que podemos introducir en uno. Hay, de hecho, hay un par de l\u00edmites, dependiendo precisamente de qu\u00e9 tipo de sistema estemos hablando.<\/p>\n\n\n\n<p>En un extremo est\u00e1 algo llamado temperatura de Planck, y es equivalente a 1.417 x 1032 Kelvin (o algo as\u00ed como 141 millones de millones de millones de millones de millones de grados). Esto es a lo que la gente a menudo se refiere como el &#8216;calor absoluto&#8217;. Nada en el Universo de hoy se acerca a este tipo de temperaturas, pero existi\u00f3 por un breve momento justo en los albores de los tiempos. En esa fracci\u00f3n de segundo, una sola unidad de tiempo de Planck, de hecho, cuando el tama\u00f1o del Universo era solo una longitud de Planck, el movimiento aleatorio de su contenido fue lo m\u00e1s extremo posible.<\/p>\n\n\n\n<p>M\u00e1s caliente, y fuerzas como el electromagnetismo y las fuerzas nucleares estar\u00edan a la par con la fuerza de la gravedad. Explicar c\u00f3mo se ve esto exige una f\u00edsica que a\u00fan no conocemos, una que une lo que sabemos sobre la mec\u00e1nica cu\u00e1ntica con la teor\u00eda general de la relatividad de Einstein.<\/p>\n\n\n\n<p>Esas son tambi\u00e9n algunas condiciones bastante espec\u00edficas. El tiempo y el espacio nunca volver\u00e1n a estar tan confinados. Hoy en d\u00eda, lo mejor que el Universo puede manejar son los insignificantes billones de grados que creamos cuando aplastamos \u00e1tomos en un colisionador.<\/p>\n\n\n\n<p><strong>Lo opuesto al cero absoluto<br><\/strong>Pero hay otra forma de ver el calor, una que da la vuelta a toda la cuesti\u00f3n de la temperatura. Tenga en cuenta que la energ\u00eda t\u00e9rmica describe un promedio de movimientos entre las partes de un sistema. Todo lo que se necesita es un peque\u00f1o porcentaje de sus part\u00edculas volando ca\u00f3ticamente para calificar como &#8216;caliente&#8217;.<\/p>\n\n\n\n<p>Entonces, \u00bfqu\u00e9 sucede si cambiamos este estado y tenemos muchas m\u00e1s part\u00edculas r\u00e1pidas que lentas? Es lo que los f\u00edsicos llaman una distribuci\u00f3n invertida de Maxwell-Boltzman y, extra\u00f1amente, se describe usando valores que van por debajo del cero absoluto.<\/p>\n\n\n\n<p>Este extra\u00f1o sistema parece descartar el libro de reglas de la f\u00edsica. No solo lo cuantificamos como negativo al cero absoluto, es t\u00e9cnicamente m\u00e1s caliente que cualquier valor positivo. Literalmente m\u00e1s caliente que caliente.<\/p>\n\n\n\n<p>Como una peculiaridad de las estad\u00edsticas, no es algo que encontrar\u00edamos en ning\u00fan rinc\u00f3n natural del Universo. Por un lado, requerir\u00eda una cantidad infinita de energ\u00eda, y algo m\u00e1s.<\/p>\n\n\n\n<p>Eso no significa que no podamos torcer un poco las reglas y hacer algo as\u00ed. En 2013 lo demostraron f\u00edsicos de la Universidad Ludwig-Maximilians de M\u00fanich y del Instituto Max Planck de \u00d3ptica Cu\u00e1ntica de Alemania. Sin embargo, utilizaron gases at\u00f3micos en entornos muy espec\u00edficos, que imponen sus propios l\u00edmites de energ\u00eda superiores.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Absolute Zero: Absolute Awesome\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/TNUDBdv3jWI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Los resultados fueron un sistema estable de part\u00edculas con tanta energ\u00eda cin\u00e9tica que se hizo imposible introducir m\u00e1s. La \u00fanica forma de describir este arreglo en particular era usando una escala de temperatura que llegaba a Kelvin negativo, o varias mil millon\u00e9simas de grado por debajo. cero absoluto.<\/p>\n\n\n\n<p>En teor\u00eda, un estado tan extra\u00f1o podr\u00eda absorber energ\u00eda t\u00e9rmica no solo de los espacios m\u00e1s c\u00e1lidos, sino tambi\u00e9n de los m\u00e1s fr\u00edos, lo que lo convierte en un verdadero monstruo de temperaturas extremas. En este rinc\u00f3n diab\u00f3lico del Universo, una m\u00e1quina ser\u00eda capaz de tragar con una eficiencia superior al 100% mientras se alimentaba de calor y fr\u00edo por igual, pareciendo burlarse de las leyes de la termodin\u00e1mica.<\/p>\n\n\n\n<p><em>Nota de la fuente: Los verificadores de hechos determinan que todos los Explicadores son correctos y relevantes en el momento de la publicaci\u00f3n. El texto y las im\u00e1genes pueden modificarse, eliminarse o agregarse como una decisi\u00f3n editorial para mantener la informaci\u00f3n actualizada.<\/em><\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.sciencealert.com\/what-is-the-hottest-temperature\">Science Alert<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por lo que sabemos sobre nuestro Universo, la temperatura m\u00e1s fr\u00eda posible es cero grados Kelvin &#8216;absolutos&#8217;, o -273,15 \u00b0C. Pero, \u00bfqu\u00e9 pasa con la temperatura m\u00e1s alta posible? La f\u00edsica es un poco confusa sobre c\u00f3mo se ve el m\u00e1s caliente de los calientes, pero te\u00f3ricamente hablando, tal cosa existe, o al menos existi\u00f3, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-20378","post","type-post","status-publish","format-standard","hentry","category-fisica"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/20378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=20378"}],"version-history":[{"count":10,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/20378\/revisions"}],"predecessor-version":[{"id":20389,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/20378\/revisions\/20389"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=20378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=20378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=20378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}