{"id":23918,"date":"2022-07-14T03:19:28","date_gmt":"2022-07-14T08:19:28","guid":{"rendered":"https:\/\/einsteresante.com\/?p=23918"},"modified":"2022-07-14T03:19:30","modified_gmt":"2022-07-14T08:19:30","slug":"ingenieros-cultivan-un-pedazo-de-corazon-humano-que-late","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2022\/07\/14\/ingenieros-cultivan-un-pedazo-de-corazon-humano-que-late\/","title":{"rendered":"Ingenieros cultivan un pedazo de coraz\u00f3n humano que late"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aunque la investigaci\u00f3n sobre los tratamientos para las enfermedades cardiovasculares ha avanzado mucho en las \u00faltimas d\u00e9cadas, los problemas card\u00edacos a\u00fan se cobran la vida de casi 18 millones de personas en todo el mundo cada a\u00f1o. Un diminuto modelo de trabajo de un ventr\u00edculo humano podr\u00eda abrir nuevos caminos en el desarrollo de nuevos f\u00e1rmacos y terapias, y para estudiar el desarrollo de enfermedades cardiovasculares, brindando a los investigadores una alternativa \u00e9tica y m\u00e1s precisa a los enfoques existentes. Investigadores de la Universidad de Toronto y la Universidad de Montreal en Canad\u00e1 realizaron ingenier\u00eda inversa de un vaso de un mil\u00edmetro de largo que no solo late como el verdadero, sino que bombea fluido como la c\u00e1mara de salida muscular del coraz\u00f3n de un embri\u00f3n humano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Con nuestro modelo, podemos medir el volumen de eyecci\u00f3n, la cantidad de l\u00edquido expulsado cada vez que el ventr\u00edculo se contrae, as\u00ed como la presi\u00f3n de ese l\u00edquido&#8221;, dice el ingeniero biom\u00e9dico de la Universidad de Toronto, Sargol Okhovatian.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Ambos eran casi imposibles de conseguir con los modelos anteriores&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo general, solo hay un pu\u00f1ado de opciones para estudiar las formas en que un coraz\u00f3n sano o enfermo canaliza la sangre. Los \u00f3rganos que ya no son completamente funcionales, como los que se extraen en una autopsia, brindan autenticidad sin la actividad. Los cultivos de tejidos pueden proporcionar una ventana a la funcionalidad bioqu\u00edmica, pero no capturan completamente la hidr\u00e1ulica de una masa pulsante tridimensional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un modelo animal permite a los investigadores probar c\u00f3mo un coraz\u00f3n vivo funciona como una bomba bajo la influencia de tratamientos recientemente desarrollados, pero no siempre es la opci\u00f3n m\u00e1s \u00e9tica. Uni\u00e9ndose a una ola de modelos 3D de partes del cuerpo que se desarrollan y se comportan tal como la naturaleza pretend\u00eda (sin desarrollarse en \u00f3rganos completamente funcionales), este nuevo \u00f3rgano similar a un coraz\u00f3n se cultiv\u00f3 en un laboratorio utilizando una combinaci\u00f3n de materiales sint\u00e9ticos y biol\u00f3gicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las c\u00e9lulas en s\u00ed se derivaron de los tejidos cardiovasculares de ratas j\u00f3venes y luego se cultivaron en una capa de andamio impresa de un pol\u00edmero con ranuras para dirigir el crecimiento del tejido. Esta malla plana oblig\u00f3 a la estructura a imitar la alineaci\u00f3n de las fibras musculares del coraz\u00f3n de un ventr\u00edculo izquierdo humano, la voluminosa c\u00e1mara final que lanza sangre a la aorta con un fuerte apret\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para convertir la pila de tres capas de c\u00e9lulas del coraz\u00f3n en algo que se parezca m\u00e1s a una c\u00e1mara pulsante, el equipo us\u00f3 un eje en forma de cono al que llamaron mandril. Un giro r\u00e1pido en la muestra de tejido y listo: un ventr\u00edculo simple. Todo lo que se requer\u00eda para hacer latir este diminuto tubo de c\u00e9lulas musculares card\u00edacas era una serie de peque\u00f1as descargas el\u00e9ctricas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Hasta ahora, solo ha habido un pu\u00f1ado de intentos de crear un modelo verdaderamente 3D de un ventr\u00edculo, en lugar de l\u00e1minas planas de tejido card\u00edaco&#8221;, dice la autora principal Milica Radisic, qu\u00edmica de la Universidad de Toronto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Pr\u00e1cticamente todos se han hecho con una sola capa de c\u00e9lulas. Pero un coraz\u00f3n real tiene muchas capas, y las c\u00e9lulas en cada capa est\u00e1n orientadas en diferentes \u00e1ngulos. Cuando el coraz\u00f3n late, estas capas no solo se contraen, sino que tambi\u00e9n se retuercen, un poco como cuando retuerces una toalla para escurrir el agua. Esto permite que el coraz\u00f3n bombee m\u00e1s sangre de lo que lo har\u00eda de otra manera&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con un di\u00e1metro interno de apenas medio mil\u00edmetro, el vaso apenas logra expulsar l\u00edquido a una presi\u00f3n de alrededor del 5 por ciento de la del coraz\u00f3n de un adulto. A\u00fan as\u00ed, el modelo es una gran prueba de concepto, que con el tiempo podr\u00eda aumentarse para incluir m\u00e1s capas de tejido para representar un sistema m\u00e1s fuerte. Incluso es posible que con el tiempo se pueda quitar el andamio y se pueda incorporar una mezcla de tejidos derivados de humanos, no solo mejorando la estructura como modelo, sino abriendo el camino hacia un \u00f3rgano trasplantable completamente funcional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Con estos modelos, podemos estudiar no solo la funci\u00f3n celular, sino tambi\u00e9n la funci\u00f3n de los tejidos y los \u00f3rganos, todo sin necesidad de cirug\u00eda invasiva o experimentaci\u00f3n con animales&#8221;, dice Radisic.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Tambi\u00e9n podemos usarlos para examinar grandes bibliotecas de mol\u00e9culas candidatas a f\u00e1rmacos en busca de efectos positivos o negativos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta investigaci\u00f3n fue publicada en <a rel=\"noreferrer noopener\" href=\"https:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/adbi.202101165\" target=\"_blank\">Advanced Biology<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.sciencealert.com\/engineers-have-grown-a-major-piece-of-the-heart-in-miniature-and-it-beats\">Science Alert<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque la investigaci\u00f3n sobre los tratamientos para las enfermedades cardiovasculares ha avanzado mucho en las \u00faltimas d\u00e9cadas, los problemas card\u00edacos a\u00fan se cobran la vida de casi 18 millones de personas en todo el mundo cada a\u00f1o. Un diminuto modelo de trabajo de un ventr\u00edculo humano podr\u00eda abrir nuevos caminos en el desarrollo de nuevos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-23918","post","type-post","status-publish","format-standard","hentry","category-salud-y-medicina"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/23918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=23918"}],"version-history":[{"count":5,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/23918\/revisions"}],"predecessor-version":[{"id":23923,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/23918\/revisions\/23923"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=23918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=23918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=23918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}