{"id":2538,"date":"2020-12-03T15:09:03","date_gmt":"2020-12-03T20:09:03","guid":{"rendered":"http:\/\/einsteresante.com\/?p=2538"},"modified":"2020-12-03T15:09:04","modified_gmt":"2020-12-03T20:09:04","slug":"islas-perdidas-en-el-mar-del-norte-sobrevivieron-a-tsunamis-de-hace-8000-anos","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2020\/12\/03\/islas-perdidas-en-el-mar-del-norte-sobrevivieron-a-tsunamis-de-hace-8000-anos\/","title":{"rendered":"Islas perdidas en el mar del norte sobrevivieron a tsunamis de hace 8000 a\u00f1os"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Algunas islas antiguas ahora sumergidas bajo el Mar del Norte sobrevivieron a un devastador tsunami hace unos 8.000 a\u00f1os y pueden haber desempe\u00f1ado un papel clave en la prehistoria humana de Gran Breta\u00f1a, seg\u00fan un nuevo estudio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n sugiere que algunas partes de la antigua llanura conocida como Doggerland, que conectaba Gran Breta\u00f1a con los Pa\u00edses Bajos, resistieron el enorme tsunami de Storegga que sumergi\u00f3 la mayor parte de la regi\u00f3n alrededor del 6200 a. C.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El llamado tsunami de Storegga fue causado por el colapso submarino de parte de la plataforma continental de Noruega, a unas 500 millas (800 kil\u00f3metros) al norte. Los cient\u00edficos hab\u00edan pensado durante mucho tiempo que la ola imponente sumergi\u00f3 por completo la regi\u00f3n de Doggerland entre la costa este de Inglaterra y el continente europeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la nueva investigaci\u00f3n, basada en muestras de n\u00facleos de sedimentos sumergidos durante las expediciones en barco en el Mar del Norte, sugiere que algunas partes de Doggerland sobrevivieron al antiguo tsunami y pueden haber permanecido habitadas por humanos de la Edad de Piedra durante miles de a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y si lo hicieran, las islas supervivientes de Doggerland podr\u00edan haber desempe\u00f1ado un papel en el desarrollo posterior de Gran Breta\u00f1a, como la introducci\u00f3n de la agricultura unos mil a\u00f1os despu\u00e9s, dijo el coautor del estudio Vincent Gaffney, arque\u00f3logo de la Universidad de Bradford.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Si estuvieras parado en parte de esa costa el d\u00eda que sucedi\u00f3, ser\u00eda un mal d\u00eda para ti&#8221;, dijo Gaffney a Live Science. &#8220;Sin embargo, eso no signific\u00f3 que fuera el final de Doggerland&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tierras hundidas<br><\/strong>Los cient\u00edficos creen que la regi\u00f3n ahora sumergida de Doggerland fue expuesta por la capa de hielo del norte en retirada al final de la \u00faltima edad de hielo hace unos 12.000 a\u00f1os. Hace unos 10.000 a\u00f1os, Doggerland era un paisaje de lagunas, marismas, r\u00edos, lagos y bosques; puede haber sido uno de los terrenos de caza y pesca m\u00e1s ricos de Europa durante el per\u00edodo Mesol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto Europe&#8217;s Lost Frontiers est\u00e1 liderando el esfuerzo por investigar la arqueolog\u00eda de Doggerland y reconstruir el paisaje antiguo tal como aparec\u00eda antes de hundirse bajo las olas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Descubrieron que en el momento del tsunami de Storegga, gran parte de Doggerland ya habr\u00eda estado bajo el agua debido al lento aumento del nivel del mar, dijo Gaffney.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero un notable n\u00facleo de sedimentos del lecho marino cerca del estuario ingl\u00e9s oriental del r\u00edo Ouse, conocido como Wash, muestra que la tierra permaneci\u00f3 por encima del agua muchos a\u00f1os despu\u00e9s del tsunami, y los modelos inform\u00e1ticos sugieren que otras regiones cercanas tambi\u00e9n sobrevivieron como islas aisladas, dijo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los investigadores ahora han llamado a estas islas el &#8220;Archipi\u00e9lago Dogger&#8221;, y se cree que las partes m\u00e1s altas de una regi\u00f3n central ahora conocida como &#8220;DoggerHills&#8221; tambi\u00e9n sobrevivieron al tsunami de Storegga, convirti\u00e9ndose en &#8220;Isla Dogger&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque inicialmente permanecieron en tierra firme, las islas se hundir\u00edan un poco m\u00e1s de 1000 a\u00f1os despu\u00e9s a medida que aumentara el nivel del mar, causado por el calentamiento del clima.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.mos.cms.futurecdn.net\/HwZxGc24taBsL4vuD5yeUf-1366-80.jpg\" alt=\"\"\/><figcaption>Se utilizaron dos barcos de investigaci\u00f3n, incluido el buque belga RV Belgica que se ve aqu\u00ed, para recolectar n\u00facleos de sedimentos de la regi\u00f3n de Doggerland en el Mar del Norte. (Cr\u00e9dito de la imagen: Proyecto de fronteras perdidas de Europa \/ Universidad de Bradford)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Islas sobrevivientes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas partes de Doggerland incluso pueden haber sido m\u00e1s adecuadas para los humanos despu\u00e9s de la devastaci\u00f3n del tsunami y la retirada de sus aguas, dijo Gaffney.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La gente habr\u00e1 regresado y vivido donde estaba antes, y tal vez haya sido un poco m\u00e1s abierto, y eso incluso puede haber sido bastante \u00fatil en algunas de estas \u00e1reas&#8221;, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las islas sobrevivientes pueden contener evidencia temprana de la introducci\u00f3n de tecnolog\u00edas agr\u00edcolas en Gran Breta\u00f1a, que presumiblemente se extendi\u00f3 all\u00ed desde el continente europeo, dijo. &#8220;Son estas zonas costeras donde es probable que se produzca el contacto con la agricultura y los agricultores&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ahora, los investigadores del proyecto Europa Lost Frontiers est\u00e1n trabajando para reconstruir la antigua geograf\u00eda de la regi\u00f3n de Doggerland.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un d\u00eda, esperan localizar un asentamiento de la Edad de Piedra, y las islas ahora sumergidas del Archipi\u00e9lago de Dogger est\u00e1n emergiendo como algunas de sus mejores apuestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Los \u00faltimos 20 a\u00f1os han revolucionado la forma en que entendemos a Doggerland&#8221;, dijo Gaffney. &#8220;Hemos estado bajando por valles de r\u00edos [sumergidos] para obtener datos ambientales, donde podemos obtener informaci\u00f3n sobre las plantas y animales que viv\u00edan all\u00ed. [Pero] todav\u00eda no tenemos un solo sitio de asentamiento arqueol\u00f3gico&#8221;, dijo. &#8220;Todav\u00eda es esencialmente un paisaje inexplorado&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Este art\u00edculo es una traducci\u00f3n de otro publicado en\u00a0<a href=\"https:\/\/www.livescience.com\/\">Live Science<\/a>. Puedes leer el texto original haciendo clic\u00a0<a href=\"https:\/\/www.livescience.com\/lost-island-north-sea-ancient-tsunami.html\">aqu\u00ed<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunas islas antiguas ahora sumergidas bajo el Mar del Norte sobrevivieron a un devastador tsunami hace unos 8.000 a\u00f1os y pueden haber desempe\u00f1ado un papel clave en la prehistoria humana de Gran Breta\u00f1a, seg\u00fan un nuevo estudio. La investigaci\u00f3n sugiere que algunas partes de la antigua llanura conocida como Doggerland, que conectaba Gran Breta\u00f1a con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-2538","post","type-post","status-publish","format-standard","hentry","category-geologia"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/2538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=2538"}],"version-history":[{"count":3,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/2538\/revisions"}],"predecessor-version":[{"id":2542,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/2538\/revisions\/2542"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=2538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=2538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=2538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}