{"id":2550,"date":"2020-12-04T13:15:29","date_gmt":"2020-12-04T18:15:29","guid":{"rendered":"http:\/\/einsteresante.com\/?p=2550"},"modified":"2020-12-04T13:15:31","modified_gmt":"2020-12-04T18:15:31","slug":"la-mutacion-que-permite-al-coronavirus-esquivar-anticuerpos","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2020\/12\/04\/la-mutacion-que-permite-al-coronavirus-esquivar-anticuerpos\/","title":{"rendered":"La mutaci\u00f3n que permite al coronavirus esquivar anticuerpos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los cient\u00edficos han identificado una mutaci\u00f3n del SARS-CoV-2 que permite que el virus escape al reconocimiento de varios anticuerpos fabricados como tratamientos con COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las terapias de dise\u00f1o llamadas anticuerpos monoclonales se basan en mol\u00e9culas inmunes naturales. Jesse Bloom en el Centro de Investigaci\u00f3n del C\u00e1ncer Fred Hutchinson en Seattle, Washington, y sus colegas mapearon cada posible mutaci\u00f3n del SARS-CoV-2 que podr\u00eda prevenir la uni\u00f3n de tres anticuerpos monoclonales: uno fabricado por Eli Lilly en Indian\u00e1polis, Indiana, y los dos en un &#8216;c\u00f3ctel&#8217; elaborado por Regeneron en Tarrytown, Nueva York.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las mutaciones afectan un segmento de prote\u00edna llamado dominio de uni\u00f3n al receptor, que el virus usa para unirse a las c\u00e9lulas y entrar en ellas. Los investigadores encontraron una mutaci\u00f3n que hizo que el virus escapara del reconocimiento del c\u00f3ctel de anticuerpos de Regeneron y algunas otras que lo ayudaron a escapar de uno de los tres anticuerpos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pocas de estas mutaciones est\u00e1n circulando ampliamente en personas infectadas. Pero uno prevalece en Europa, y otro se ha detectado en los Pa\u00edses Bajos y Dinamarca, donde se ha encontrado en muestras de SARS-CoV-2 tomadas de visones y personas que trabajan en granjas de visones. Los hallazgos a\u00fan no han sido revisados \u200b\u200bpor pares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.nature.com\/articles\/d41586-020-00502-w\">Nature<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cient\u00edficos han identificado una mutaci\u00f3n del SARS-CoV-2 que permite que el virus escape al reconocimiento de varios anticuerpos fabricados como tratamientos con COVID-19. Las terapias de dise\u00f1o llamadas anticuerpos monoclonales se basan en mol\u00e9culas inmunes naturales. Jesse Bloom en el Centro de Investigaci\u00f3n del C\u00e1ncer Fred Hutchinson en Seattle, Washington, y sus colegas mapearon [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2550","post","type-post","status-publish","format-standard","hentry","category-salud-y-medicina"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/2550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=2550"}],"version-history":[{"count":1,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/2550\/revisions"}],"predecessor-version":[{"id":2552,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/2550\/revisions\/2552"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=2550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=2550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=2550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}