{"id":48561,"date":"2024-01-25T21:46:51","date_gmt":"2024-01-26T02:46:51","guid":{"rendered":"https:\/\/einsteresante.com\/?p=48561"},"modified":"2024-01-25T21:46:52","modified_gmt":"2024-01-26T02:46:52","slug":"tratamiento-contra-la-hepatitis-impide-el-progreso-de-un-tipo-comun-de-cancer-sanguineo","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2024\/01\/25\/tratamiento-contra-la-hepatitis-impide-el-progreso-de-un-tipo-comun-de-cancer-sanguineo\/","title":{"rendered":"Tratamiento contra la hepatitis impide el progreso de un tipo com\u00fan de c\u00e1ncer sangu\u00edneo"},"content":{"rendered":"\n<p>La notable recuperaci\u00f3n de un paciente del mieloma m\u00faltiple, un c\u00e1ncer com\u00fan de la sangre, hace varios a\u00f1os ha llamado la atenci\u00f3n de los investigadores, quienes quedaron at\u00f3nitos por el hecho de que el paciente fue tratado por una enfermedad completamente diferente. El inter\u00e9s en la posible conexi\u00f3n ha llevado ahora a un equipo espa\u00f1ol y franc\u00e9s a descubrir que el virus de la hepatitis B (VHB) y el virus de la hepatitis C (VHC) est\u00e1n relacionados con el desarrollo del mieloma m\u00faltiple y etapas anteriores no cancerosas conocidas como gammapat\u00edas monoclonales. Su estudio reciente confirma que la detecci\u00f3n temprana de la hepatitis B y C podr\u00eda ayudar a los m\u00e9dicos a prevenir que las gammapat\u00edas monoclonales progresen hasta convertirse en c\u00e1ncer mediante el tratamiento de estas infecciones virales.<\/p>\n\n\n\n<p>&#8220;Demostramos que la terapia antiviral mejora la supervivencia de los pacientes con mieloma m\u00faltiple VHB positivo&#8221;, escriben en su art\u00edculo publicado la cient\u00edfica biom\u00e9dica Alba Rodr\u00edguez-Garc\u00eda de la Unidad de Investigaci\u00f3n Cl\u00ednica de Neoplasias Hematol\u00f3gicas de Espa\u00f1a y sus colegas.<\/p>\n\n\n\n<p>&#8220;Nuestro estudio tambi\u00e9n confirma en una cohorte grande que el tratamiento antiviral mejora el resultado del mieloma m\u00faltiple en pacientes infectados por el VHC&#8221;.<\/p>\n\n\n\n<p>El mieloma m\u00faltiple es un c\u00e1ncer que se desarrolla en la m\u00e9dula \u00f3sea a partir de c\u00e9lulas plasm\u00e1ticas anormales, un tipo de gl\u00f3bulo blanco que normalmente produce anticuerpos para combatir infecciones. La enfermedad se caracteriza por m\u00faltiples tumores.<\/p>\n\n\n\n<p>Las c\u00e9lulas plasm\u00e1ticas anormales proliferan y producen demasiada cantidad de un anticuerpo, lo que var\u00eda en cada caso. Este anticuerpo, llamado prote\u00edna del mieloma, se puede utilizar como biomarcador para indicar la presencia de c\u00e1ncer o una afecci\u00f3n similar. Antes del mieloma m\u00faltiple, existen etapas anteriores llamadas gammapat\u00eda monoclonal de significado indeterminado (GMSI) y mieloma latente (SMM).<\/p>\n\n\n\n<p>La investigaci\u00f3n y el tratamiento del mieloma m\u00faltiple han avanzado, pero la enfermedad todav\u00eda se considera incurable. Algunos estudios han relacionado la exposici\u00f3n cr\u00f3nica a sustancias espec\u00edficas (subproductos virales, por ejemplo) con la GMSI y el mieloma m\u00faltiple. La leucemia linfoc\u00edtica cr\u00f3nica y el linfoma (dos enfermedades que involucran receptores necesarios para reconocer anticuerpos) tambi\u00e9n se han relacionado con infecciones a largo plazo.<\/p>\n\n\n\n<p>Los investigadores tambi\u00e9n han encontrado v\u00ednculos entre el mieloma m\u00faltiple y las infecciones por otros virus como el VIH o el virus de Epstein-Barr. Averiguar qu\u00e9 intentan atacar los anticuerpos del paciente puede ayudar a controlar la enfermedad.<\/p>\n\n\n\n<p>El mismo grupo public\u00f3 anteriormente un estudio en 2022 en el que participaron nueve pacientes con hepatitis C y gammapat\u00eda monoclonal. Los que fueron tratados con medicaci\u00f3n antiviral mostraron una mayor mejor\u00eda en el mieloma m\u00faltiple o la gammapat\u00eda monoclonal en comparaci\u00f3n con los que no lo fueron. A\u00fan m\u00e1s alentador: la medicaci\u00f3n antiviral puso a uno de esos pacientes con mieloma m\u00faltiple en remisi\u00f3n completa a largo plazo, al parecer durante al menos cuatro a\u00f1os en ese momento.<\/p>\n\n\n\n<p>El nuevo estudio de Rodr\u00edguez-Garc\u00eda y su equipo involucr\u00f3 a 45 pacientes con gammapat\u00eda monoclonal y hepatitis B. En el 36,7% de los casos en los que pudieron detectar el tipo de anticuerpos excesivos que se produc\u00edan, se dirigi\u00f3 espec\u00edficamente al VHB, lo que sugiere que su gammapat\u00eda fue impulsada por el VHB. Al recibir tratamiento antiviral, la gammapat\u00eda de dos de esos pacientes no progres\u00f3.<\/p>\n\n\n\n<p>Luego observaron un grupo m\u00e1s grande de m\u00e1s de 2500 pacientes de mieloma m\u00faltiple con hepatitis B o C. En ambos grupos, encontraron que aquellos que recibieron tratamiento antiviral ten\u00edan mayores posibilidades de supervivencia.<\/p>\n\n\n\n<p>&#8220;Este estudio demuestra la importancia de los tratamientos antivirales para pacientes con gammapat\u00edas clonales provocadas por el VHB o el VHC, incluido el mieloma m\u00faltiple&#8221;, concluyen los autores.<\/p>\n\n\n\n<p>&#8220;La terapia antiviral debe prescribirse lo antes posible en el desarrollo de gammapat\u00edas clonales ligadas al VHB o al VHC, idealmente en la etapa de GMSI&#8221;.<\/p>\n\n\n\n<p>La investigaci\u00f3n ha sido publicada en <a href=\"https:\/\/doi.org\/10.3324\/haematol.2023.283096\">Haematologica<\/a>.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.sciencealert.com\/hepatitis-treatment-prevents-the-progress-of-a-common-blood-cancer\">Science Alert<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La notable recuperaci\u00f3n de un paciente del mieloma m\u00faltiple, un c\u00e1ncer com\u00fan de la sangre, hace varios a\u00f1os ha llamado la atenci\u00f3n de los investigadores, quienes quedaron at\u00f3nitos por el hecho de que el paciente fue tratado por una enfermedad completamente diferente. El inter\u00e9s en la posible conexi\u00f3n ha llevado ahora a un equipo espa\u00f1ol [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-48561","post","type-post","status-publish","format-standard","hentry","category-salud-y-medicina"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/48561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=48561"}],"version-history":[{"count":7,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/48561\/revisions"}],"predecessor-version":[{"id":48569,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/48561\/revisions\/48569"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=48561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=48561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=48561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}