{"id":53715,"date":"2024-05-08T08:12:42","date_gmt":"2024-05-08T13:12:42","guid":{"rendered":"https:\/\/einsteresante.com\/?p=53715"},"modified":"2024-05-08T08:12:43","modified_gmt":"2024-05-08T13:12:43","slug":"cientificos-creen-haber-encontrado-nuestra-brujula-neuronal-que-impide-que-nos-perdamos","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2024\/05\/08\/cientificos-creen-haber-encontrado-nuestra-brujula-neuronal-que-impide-que-nos-perdamos\/","title":{"rendered":"Cient\u00edficos creen haber encontrado nuestra &#8220;br\u00fajula neuronal&#8221; que impide que nos perdamos"},"content":{"rendered":"\n<p>Para mantener nuestros cuerpos correctamente orientados, nuestros cerebros realizan impresionantes haza\u00f1as de c\u00e1lculo que rastrean nuestro tambaleante saco de carne a trav\u00e9s de un mapa mental de nuestro entorno. Si bien muchas investigaciones se han centrado en el mapeo, pocas han logrado determinar c\u00f3mo nuestro cableado neurol\u00f3gico monitorea nuestra direcci\u00f3n dentro de \u00e9l.<\/p>\n\n\n\n<p>Un equipo de investigadores de la Universidad de Birmingham en el Reino Unido y la Universidad Ludwig Maximilian de M\u00fanich en Alemania ha identificado una actividad cerebral caracter\u00edstica que describe una especie de &#8220;br\u00fajula neuronal&#8221; con la esperanza de comprender c\u00f3mo nos orientamos en el mundo. Incluso el m\u00e1s m\u00ednimo error en t\u00e9rminos de hacia d\u00f3nde apunta nuestro cuerpo y hacia d\u00f3nde miramos puede causar problemas, ya sea al cruzar una puerta o conducir un autom\u00f3vil, y el estudio tambi\u00e9n puede servir de base para la investigaci\u00f3n de enfermedades neurodegenerativas como el Alzheimer.<\/p>\n\n\n\n<p>&#8220;Sabemos que animales como p\u00e1jaros, ratas y murci\u00e9lagos tienen circuitos neuronales que los mantienen encaminados, pero sabemos sorprendentemente poco sobre c\u00f3mo el cerebro humano maneja esto en el mundo real&#8221;, dice el neurocient\u00edfico Benjamin Griffiths, de la Universidad de Birmingham.<\/p>\n\n\n\n<p>En dos experimentos separados, Griffiths y sus colegas instaron a 52 voluntarios sanos a orientar sus cabezas y ojos de diferentes maneras mientras monitoreaban las se\u00f1ales cerebrales a trav\u00e9s de gorros de electroencefalograma (EEG) conectados al cuero cabelludo y registraban sus movimientos con seguimiento de movimiento. Se realizaron m\u00e1s pruebas en 10 voluntarios que ya ten\u00edan electrodos dentro del cr\u00e1neo para enfermedades como la epilepsia. Esto le dio al equipo una visi\u00f3n a\u00fan m\u00e1s cercana de las regiones del cerebro que se iluminaban con actividad cuando se mov\u00edan la cabeza y los ojos. Al descartar las influencias en la activaci\u00f3n neuronal del movimiento muscular y la informaci\u00f3n sensorial, los investigadores identificaron regiones en el l\u00f3bulo temporal medial (implicado en la memoria), la corteza parietal (implicada en la vinculaci\u00f3n de la informaci\u00f3n entrante) y el parahipocampo (implicado en el reconocimiento de lugares) como contribuyentes importantes a nuestra br\u00fajula neuronal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/05\/image-23.png\" alt=\"\" class=\"wp-image-53727\"\/><figcaption class=\"wp-element-caption\">Los investigadores compararon las se\u00f1ales cerebrales con los movimientos de la cabeza. Griffiths et al., Nature Human Behaviour, 2024.<\/figcaption><\/figure>\n\n\n\n<p>&#8220;Varias regiones distintas est\u00e1n sintonizadas con los cambios en el \u00e1ngulo de la cabeza, incluido el l\u00f3bulo parietal y el parahipocampo&#8221;, explican los investigadores en su art\u00edculo. &#8220;Identificamos una firma sintonizada con el \u00e1ngulo de rumbo actual que se distingue de la informaci\u00f3n sensorial y la actividad muscular&#8221;.<\/p>\n\n\n\n<p>Las se\u00f1ales en estas regiones se enviaron justo antes de los movimientos de la cabeza, lo que sugiere que desempe\u00f1an un papel crucial para hacernos mirar como debemos estar y garantizar que no perdamos de vista d\u00f3nde estamos en un entorno.<\/p>\n\n\n\n<p>&#8220;Aislar estas se\u00f1ales nos permite centrarnos realmente en c\u00f3mo el cerebro procesa la informaci\u00f3n de navegaci\u00f3n y c\u00f3mo estas se\u00f1ales funcionan junto con otras se\u00f1ales, como los puntos de referencia visuales&#8221;, dice Griffiths.<\/p>\n\n\n\n<p>Con una mejor comprensi\u00f3n de c\u00f3mo el cerebro dirige nuestro cuerpo, podr\u00edamos ayudar a evitar que esta parte particular del circuito neuronal se descomponga. El equipo de estudio tambi\u00e9n sugiere que la investigaci\u00f3n sobre tecnolog\u00eda de navegaci\u00f3n tambi\u00e9n podr\u00eda beneficiarse.<\/p>\n\n\n\n<p>Los nuevos hallazgos tambi\u00e9n son interesantes en el contexto de nuestra creciente dependencia del uso de la tecnolog\u00eda para orientarnos. Podr\u00eda ser que nuestra br\u00fajula neuronal haya sido descubierta incluso cuando nuestra dependencia de ella se reduce.<\/p>\n\n\n\n<p>&#8220;Nuestro enfoque ha abierto nuevas v\u00edas para explorar estas caracter\u00edsticas, con implicaciones para la investigaci\u00f3n de enfermedades neurodegenerativas e incluso para mejorar las tecnolog\u00edas de navegaci\u00f3n en rob\u00f3tica e inteligencia artificial&#8221;, dice Griffiths.<\/p>\n\n\n\n<p>La investigaci\u00f3n ha sido publicada <a href=\"https:\/\/www.nature.com\/articles\/s41562-024-01872-1\">Nature Human Behaviour<\/a>.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.sciencealert.com\/scientists-think-theyve-found-our-neural-compass-that-stops-us-getting-lost\">Science Alert<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para mantener nuestros cuerpos correctamente orientados, nuestros cerebros realizan impresionantes haza\u00f1as de c\u00e1lculo que rastrean nuestro tambaleante saco de carne a trav\u00e9s de un mapa mental de nuestro entorno. Si bien muchas investigaciones se han centrado en el mapeo, pocas han logrado determinar c\u00f3mo nuestro cableado neurol\u00f3gico monitorea nuestra direcci\u00f3n dentro de \u00e9l. Un equipo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-53715","post","type-post","status-publish","format-standard","hentry","category-biologia"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/53715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=53715"}],"version-history":[{"count":12,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/53715\/revisions"}],"predecessor-version":[{"id":53728,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/53715\/revisions\/53728"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=53715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=53715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=53715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}