{"id":53885,"date":"2024-05-12T12:31:18","date_gmt":"2024-05-12T17:31:18","guid":{"rendered":"https:\/\/einsteresante.com\/?p=53885"},"modified":"2024-05-12T12:31:19","modified_gmt":"2024-05-12T17:31:19","slug":"gatos-ferales-comieron-cocodrilos-bebe-en-peligro-critico-de-extincion-en-cuba-sugiere-estudio","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2024\/05\/12\/gatos-ferales-comieron-cocodrilos-bebe-en-peligro-critico-de-extincion-en-cuba-sugiere-estudio\/","title":{"rendered":"Gatos ferales comieron cocodrilos beb\u00e9 en peligro cr\u00edtico de extinci\u00f3n en Cuba, sugiere estudio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los gatos salvajes mataban y com\u00edan cocodrilos beb\u00e9s en Cuba, sugiere nueva evidencia. Esto es preocupante porque el cocodrilo cubano (<em>Crocodylus rhombifer<\/em>) es una especie en peligro cr\u00edtico de extinci\u00f3n que vive s\u00f3lo en los pantanos de Zapata y Lanier en Cuba. Varias caracter\u00edsticas distinguen al cocodrilo cubano de otras especies de cocodrilos del Nuevo Mundo, incluidas las crestas \u00f3seas detr\u00e1s de los ojos, un temperamento inusualmente curioso y agresivo y la capacidad de saltar alto fuera del agua, seg\u00fan George Amato, director em\u00e9rito del Instituto de Gen\u00f3mica Comparada del Museo Americano de Historia Natural y experto en cocodrilos cubanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cocodrilo cubano representa &#8220;un linaje evolutivo muy antiguo&#8221; y juega un papel importante en su ecosistema nativo, dijo Amato a Live Science. Ha estado trabajando con la especie desde la d\u00e9cada de 1990.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se estima que s\u00f3lo quedan unos 3.000 cocodrilos cubanos en estado salvaje, por lo que los humanos est\u00e1n tratando de aumentar la poblaci\u00f3n. Cada a\u00f1o, la Granja de Crianza de Cocodrilos del Pantano de Zapata, la operaci\u00f3n de cr\u00eda de cocodrilos cubana m\u00e1s grande del mundo, libera unos 500 cocodrilos cubanos en el pantano, con la esperanza de que florezcan y se reproduzcan, dijo Etiam P\u00e9rez-Fleitas, bi\u00f3logo afiliado a la granja, a Live Science en un correo electr\u00f3nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De octubre a noviembre de 2022, la granja, que seg\u00fan P\u00e9rez-Fleitas gestiona hoy alrededor de 4.500 cocodrilos cubanos, sufri\u00f3 una serie de ataques depredadores que mataron a 145 cocodrilos de 4 meses, seg\u00fan un art\u00edculo publicado en l\u00ednea el 19 de abril en la revista <a href=\"https:\/\/www.biotaxa.org\/hn\/article\/view\/83056\" target=\"_blank\" rel=\"noreferrer noopener\">Herpetology Notes<\/a>. En el art\u00edculo, los coautores P\u00e9rez-Fleitas y Gustavo Sosa-Rodr\u00edguez describieron evidencia de que los gatos salvajes fueron responsables de los ataques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Dir\u00eda que esta es la primera vez que tengo conocimiento de que existe una sugerencia de que los gatos salvajes podr\u00edan ser un problema para los cocodrilos&#8221;, dijo Amato, que no particip\u00f3 en la nueva investigaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/05\/image-32.png\" alt=\"\" class=\"wp-image-53896\"\/><figcaption class=\"wp-element-caption\">Los cient\u00edficos encontraron las cabezas cortadas de tres cr\u00edas de cocodrilo en 2022, y varias l\u00edneas de evidencia sugirieron que los gatos salvajes eran los culpables de la depredaci\u00f3n. Cr\u00e9dito de la imagen: Foto de Etiam P\u00e9rez-Fleitas.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las pistas de que los gatos fueron los responsables incluyen marcas sospechosas y pelo recuperado en los alrededores. Las c\u00e1maras trampa tambi\u00e9n registraron al menos un gato entrando en los corrales de cocodrilos. Y en una ocasi\u00f3n, el personal de la granja vio a varios gatos aliment\u00e1ndose de algo cercano. Cuando fueron a investigar, encontraron &#8220;fragmentos de cocodrilos&#8221;, seg\u00fan el art\u00edculo. Es m\u00e1s, los ataques cesaron un mes despu\u00e9s de que siete gatos salvajes fueran capturados y retirados de la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No obtuvimos evidencia de otros depredadores presentes en estos recintos&#8221;, dijo P\u00e9rez-Fleitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto Amato como P\u00e9rez-Fleitas dijeron a Live Science que no creen que los gatos salvajes representen una amenaza existencial para el cocodrilo cubano, y Amato cit\u00f3 las condiciones artificiales bajo las cuales ocurrieron los ataques. Despu\u00e9s de todo, se\u00f1al\u00f3, los cocodrilos j\u00f3venes no se encuentran encerrados en grandes cantidades en \u00e1reas cerradas en la naturaleza, como ocurre en las granjas. En cambio, dijo Amato, los hallazgos subrayan que los gatos que deambulan libremente pueden causar estragos en los entornos en los que se introducen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/05\/image-33.png\" alt=\"\" class=\"wp-image-53898\"\/><figcaption class=\"wp-element-caption\">Las c\u00e1maras trampa capturaron a un gato salvaje entrando a los corrales de los cocodrilos. Cr\u00e9dito de la imagen: Recuperado de Etiam P\u00e9rez-Fleitas y Gustavo Sosa Rodr\u00edguez.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Los gatos salvajes claramente tienen un impacto significativo en las poblaciones silvestres, m\u00e1s de lo que creo que la gente pensaba&#8221;, dijo Amato. &#8220;Y no se trata s\u00f3lo de gatos salvajes. Son gatos dom\u00e9sticos que, ya sabes, tambi\u00e9n est\u00e1n afuera&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Clasificado en el puesto 38 en una lista de 100 de las &#8220;peores especies ex\u00f3ticas invasoras del mundo&#8221;, se estima que los gatos callejeros matan anualmente miles de millones de aves y mam\u00edferos en los Estados Unidos y han estado implicados en una serie de extinciones en todo el mundo. En respuesta al da\u00f1o resultante a los ecosistemas nativos, algunas organizaciones y gobiernos han adoptado medidas de mitigaci\u00f3n controvertidas, que incluyen trampas, disparos y envenenamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la luz de los ataques, P\u00e9rez-Fleitas dijo que \u00e9l y sus colegas est\u00e1n &#8220;monitoreando \u00e1reas donde existen poblaciones de cocodrilos cubanos para estimar el tama\u00f1o de la poblaci\u00f3n de gatos salvajes, si es que existen en esos lugares&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si las poblaciones son lo suficientemente peque\u00f1as, esterilizar a los gatos machos puede ser suficiente para proteger a los cocodrilos, dijo P\u00e9rez-Fleitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, &#8220;en lugares donde las poblaciones eran abundantes&#8221;, a\u00f1adi\u00f3, &#8220;lamentablemente nuestra recomendaci\u00f3n ser\u00e1 utilizar m\u00e9todos letales para reducir su tama\u00f1o efectivo y luego esterilizarlos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Live Science.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los gatos salvajes mataban y com\u00edan cocodrilos beb\u00e9s en Cuba, sugiere nueva evidencia. Esto es preocupante porque el cocodrilo cubano (Crocodylus rhombifer) es una especie en peligro cr\u00edtico de extinci\u00f3n que vive s\u00f3lo en los pantanos de Zapata y Lanier en Cuba. Varias caracter\u00edsticas distinguen al cocodrilo cubano de otras especies de cocodrilos del Nuevo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-53885","post","type-post","status-publish","format-standard","hentry","category-medio-ambiente"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/53885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=53885"}],"version-history":[{"count":12,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/53885\/revisions"}],"predecessor-version":[{"id":53899,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/53885\/revisions\/53899"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=53885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=53885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=53885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}