{"id":56260,"date":"2024-06-28T14:39:27","date_gmt":"2024-06-28T19:39:27","guid":{"rendered":"https:\/\/einsteresante.com\/?p=56260"},"modified":"2024-06-28T14:39:28","modified_gmt":"2024-06-28T19:39:28","slug":"la-nasa-escoge-a-spacex-para-destruir-la-estacion-espacial-internacional","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2024\/06\/28\/la-nasa-escoge-a-spacex-para-destruir-la-estacion-espacial-internacional\/","title":{"rendered":"La NASA escoge a SpaceX para destruir la Estaci\u00f3n Espacial Internacional"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La NASA dijo el martes que hab\u00eda elegido a SpaceX para construir una nave que transportar\u00eda la Estaci\u00f3n Espacial Internacional (ISS) de regreso a trav\u00e9s de la atm\u00f3sfera de la Tierra y a un lugar de descanso final en el Oc\u00e9ano Pac\u00edfico despu\u00e9s de su retiro en 2030. La compa\u00f1\u00eda de Elon Musk obtuvo un contrato con un valor potencial de 843 millones de d\u00f3lares para desarrollar y entregar la nave espacial, denominada Veh\u00edculo de Desorbitaci\u00f3n Estadounidense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La selecci\u00f3n de un veh\u00edculo de salida de \u00f3rbita estadounidense para la Estaci\u00f3n Espacial Internacional ayudar\u00e1 a la NASA y a sus socios internacionales a garantizar una transici\u00f3n segura y responsable a la \u00f3rbita terrestre baja al final de las operaciones de la estaci\u00f3n&#8221;, dijo Ken Bowersox de la NASA en un comunicado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/06\/image-59.png\" alt=\"\" class=\"wp-image-56266\"\/><figcaption class=\"wp-element-caption\">Los astronautas Jessica Watkins y Bob Hines cultivan plantas en la ISS en 2022. NASA.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La NASA planea tomar posesi\u00f3n de la nave espacial despu\u00e9s de que SpaceX la construya y controlar las operaciones durante toda la misi\u00f3n. Con un peso de 430.000 kilogramos, la ISS es, con diferencia, la estructura m\u00e1s grande jam\u00e1s construida en el espacio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/06\/image-60.png\" alt=\"\" class=\"wp-image-56268\"\/><figcaption class=\"wp-element-caption\">La Estaci\u00f3n Espacial Internacional fotografiada desde el SpaceX Crew Dragon Endeavor en 2021. NASA.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Bas\u00e1ndose en observaciones pasadas de c\u00f3mo otras estaciones como Mir y Skylab se desintegraron en el reingreso a la atm\u00f3sfera, los ingenieros de la NASA esperan que el puesto orbital se rompa en tres etapas. Primero, los enormes paneles solares y los radiadores que mantienen fresco el laboratorio orbital se desprender\u00e1n, luego los m\u00f3dulos individuales se desprender\u00e1n de la armadura o estructura principal de la estaci\u00f3n. Finalmente, la armadura y los propios m\u00f3dulos se romper\u00e1n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/06\/image-61.png\" alt=\"\" class=\"wp-image-56270\"\/><figcaption class=\"wp-element-caption\">Una secci\u00f3n de paneles solares sobre la Aurora Boreal vista desde la ISS en 2012. NASA.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Gran parte del material se vaporizar\u00e1, pero se espera que sobrevivan trozos grandes. Por este motivo, la NASA apunta a una zona del Oc\u00e9ano Pac\u00edfico llamada Punto Nemo, una de las zonas m\u00e1s remotas del mundo y conocida como el cementerio de sat\u00e9lites y naves espaciales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/06\/image-62.png\" alt=\"\" class=\"wp-image-56272\"\/><figcaption class=\"wp-element-caption\">Los astronautas Robert L. Curbeam Jr. y Christer Fuglesang participan en una actividad extravehicular (EVA) en la ISS. NASA.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El primer segmento de la ISS se lanz\u00f3 en 1998 y ha estado continuamente habitado por una tripulaci\u00f3n internacional desde 2001. Estados Unidos, Jap\u00f3n, Canad\u00e1 y los pa\u00edses participantes de la Agencia Espacial Europea (ESA) se han comprometido a operar el laboratorio de microgravedad a trav\u00e9s de 2030, aunque Rusia, el quinto socio, solo se ha comprometido a operar hasta 2028.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe de la NASA, Bill Nelson, dijo al Congreso en abril que, dado el terrible estado de las relaciones entre Estados Unidos y Rusia, ser\u00eda prudente comenzar a trabajar en un veh\u00edculo de desorbitaci\u00f3n estadounidense para &#8220;bajar toda la estaci\u00f3n de manera segura, de modo que no golpee a nadie ni a nada&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Varias empresas est\u00e1n trabajando en sucesores comerciales de la ISS, entre ellos, en particular, Axiom Space y Blue Origin de Jeff Bezos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.sciencealert.com\/nasa-picks-spacex-to-destroy-the-international-space-station\">Science Alert<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NASA dijo el martes que hab\u00eda elegido a SpaceX para construir una nave que transportar\u00eda la Estaci\u00f3n Espacial Internacional (ISS) de regreso a trav\u00e9s de la atm\u00f3sfera de la Tierra y a un lugar de descanso final en el Oc\u00e9ano Pac\u00edfico despu\u00e9s de su retiro en 2030. La compa\u00f1\u00eda de Elon Musk obtuvo un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-56260","post","type-post","status-publish","format-standard","hentry","category-astronautica"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/56260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=56260"}],"version-history":[{"count":11,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/56260\/revisions"}],"predecessor-version":[{"id":56275,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/56260\/revisions\/56275"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=56260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=56260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=56260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}