{"id":64101,"date":"2024-11-21T00:00:23","date_gmt":"2024-11-21T05:00:23","guid":{"rendered":"https:\/\/einsteresante.com\/?p=64101"},"modified":"2024-11-21T00:00:23","modified_gmt":"2024-11-21T05:00:23","slug":"nuevos-hallazgos-del-desi-confirman-que-la-gravedad-de-einstein-funciona-por-miles-de-millones-de-anos-luz","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2024\/11\/21\/nuevos-hallazgos-del-desi-confirman-que-la-gravedad-de-einstein-funciona-por-miles-de-millones-de-anos-luz\/","title":{"rendered":"Nuevos hallazgos del DESI confirman  que la gravedad de Einstein funciona por miles de millones de a\u00f1os luz"},"content":{"rendered":"\n<p>En el Observatorio Nacional Kitt Peak, cerca de Tucson, Arizona, un telescopio observa el cosmos y registra la ubicaci\u00f3n de millones de galaxias. El telescopio de cuatro metros est\u00e1 cartografiando actualmente el universo para resolver uno de los mayores enigmas de la astrof\u00edsica: \u00bfpor qu\u00e9 el universo se expande m\u00e1s r\u00e1pido a medida que pasa el tiempo?<\/p>\n\n\n\n<p>Ahora, una colaboraci\u00f3n multiinstitucional de m\u00e1s de 900 investigadores de m\u00e1s de 70 instituciones de todo el mundo proporcion\u00f3 resultados compartidos publicados en el repositorio en l\u00ednea <a href=\"https:\/\/data.desi.lbl.gov\/doc\/papers\/\">arXiv<\/a>. Resulta que, una vez m\u00e1s, la teor\u00eda de la relatividad general de Einstein se mantiene. Esta vez en una escala de mil millones de a\u00f1os luz.<\/p>\n\n\n\n<p>Basados \u200b\u200ben observaciones de seis millones de galaxias utilizando el Instrumento Espectrosc\u00f3pico de Energ\u00eda Oscura (DESI) del telescopio, montado en el Telescopio Nicholas U. Mayall de 4 metros de la Fundaci\u00f3n Nacional de Ciencias de Estados Unidos en Kitt Peak, los hallazgos tambi\u00e9n apuntan a una historia m\u00e1s profunda sobre la energ\u00eda oscura, el motor detr\u00e1s de esta expansi\u00f3n acelerada. Durante m\u00e1s de un siglo, la Relatividad General ha explicado la atracci\u00f3n de la gravedad en nuestro sistema solar y m\u00e1s all\u00e1. Los \u00faltimos hallazgos de DESI extienden esa validaci\u00f3n a las mayores escalas observables. Al mapear la distribuci\u00f3n de las galaxias, los investigadores han demostrado que el modelo de gravedad de Einstein sigue siendo v\u00e1lido incluso cuando se aplica a lo largo de miles de millones de a\u00f1os de historia c\u00f3smica. El an\u00e1lisis estuvo a cargo del f\u00edsico Mustapha Ishak-Boushaki, de la Universidad de Texas en Dallas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/11\/image-70.png\" alt=\"\" class=\"wp-image-64109\"\/><figcaption class=\"wp-element-caption\">Esta simulaci\u00f3n muestra c\u00f3mo la mayor o menor gravedad afecta las posiciones de las galaxias que observamos, modificando la forma en que se agrupan en un mapa de galaxias. Debido a que los diferentes modelos de gravedad predicen diferentes agrupaciones de galaxias, los investigadores de DESI pueden comparar las observaciones con simulaciones para probar la gravedad a escalas c\u00f3smicas. Cr\u00e9dito: Claire Lamman y Michael Rashkovetskyi \/ Colaboraci\u00f3n DESI.<\/figcaption><\/figure>\n\n\n\n<p>\u201cPara esta ronda de resultados de DESI, concentr\u00e9 mis esfuerzos en UT Dallas en realizar una gran parte del an\u00e1lisis sobre la gravedad, que impone restricciones sobre c\u00f3mo se mueve la materia en el universo y c\u00f3mo evolucionan las estructuras a gran escala, como los c\u00famulos de galaxias\u201d, dijo Ishak-Boushaki, un astrof\u00edsico cuya carrera de investigaci\u00f3n se ha centrado en cuestiones de cosmolog\u00eda.<\/p>\n\n\n\n<p>\u201cLos resultados de DESI, combinados con conjuntos de datos de otros experimentos, son consistentes con la teor\u00eda de la relatividad general que opera a escalas c\u00f3smicas, aunque no excluyen por completo otras teor\u00edas de gravedad modificada\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2024\/11\/image-71.png\" alt=\"\" class=\"wp-image-64111\"\/><figcaption class=\"wp-element-caption\">El instrumento espectrosc\u00f3pico de energ\u00eda oscura (DESI) realiza observaciones en el cielo nocturno a bordo del telescopio Nicholas U. Mayall de 4 metros en el Observatorio Nacional Kitt Peak en Arizona. Cr\u00e9dito: KPNO\/NOIRLab\/NSF\/AURA\/T. Slovinsk\u00fd.<\/figcaption><\/figure>\n\n\n\n<p>El an\u00e1lisis complejo utiliz\u00f3 casi 6 millones de galaxias y cu\u00e1sares y permite a los investigadores ver hasta 11 mil millones de a\u00f1os en el pasado. Con tan solo un a\u00f1o de datos, DESI ha realizado la medici\u00f3n global m\u00e1s precisa del crecimiento de la estructura, superando los esfuerzos previos que tardaron d\u00e9cadas en realizarse.<\/p>\n\n\n\n<p>Sin embargo, el esfuerzo no ha terminado. Los investigadores siguen investigando teor\u00edas de gravedad modificada para ayudar a explicar por qu\u00e9 la expansi\u00f3n del cosmos se est\u00e1 acelerando. Los resultados de DESI apuntan actualmente a Einstein, pero otras teor\u00edas no est\u00e1n totalmente descartadas.<\/p>\n\n\n\n<p>Al registrar simult\u00e1neamente la luz de 5.000 galaxias, DESI puede generar un mapa tridimensional del cosmos. Esto permite a los cient\u00edficos rastrear el desarrollo de las formaciones c\u00f3smicas a lo largo del tiempo. Al examinar c\u00f3mo se agrupa la materia en varios niveles, el an\u00e1lisis m\u00e1s reciente adopta una visi\u00f3n amplia, examinando c\u00f3mo se agrupa la materia en diferentes escalas.<\/p>\n\n\n\n<p>Los resultados van m\u00e1s all\u00e1 del simple apoyo a la relatividad. Respaldan la teor\u00eda de que la energ\u00eda oscura podr\u00eda no ser continua. M\u00e1s bien, podr\u00eda desarrollarse, alterando su influencia en el cosmos a lo largo del tiempo.<\/p>\n\n\n\n<p>\u201cLa materia oscura constituye aproximadamente una cuarta parte del universo, y la energ\u00eda oscura constituye otro 70%, y no sabemos realmente qu\u00e9 es ni lo uno ni lo otro\u201d, dijo Mark Maus, estudiante de doctorado en Berkeley Lab y la UC Berkeley, que trabaj\u00f3 en la teor\u00eda y en los procesos de modelado de validaci\u00f3n para el nuevo an\u00e1lisis. \u201cLa idea de que podemos tomar fotograf\u00edas del universo y abordar estas grandes preguntas fundamentales es alucinante\u201d.<\/p>\n\n\n\n<p>Los datos de DESI no se limitan a probar teor\u00edas de la gravedad. Tambi\u00e9n hacen hincapi\u00e9 en los neutrinos, part\u00edculas tan diminutas y esquivas que sus caracter\u00edsticas siguen siendo en su mayor\u00eda desconocidas. Los resultados de DESI redujeron el rango concebible de masas de neutrinos, lo cual es esencial en relaci\u00f3n con su impacto en el universo. Estas part\u00edculas, casi sin peso, interact\u00faan d\u00e9bilmente con otra materia. Sin embargo, su masa combinada desempe\u00f1a un papel en la conformaci\u00f3n del cosmos, afectando a c\u00f3mo se forman y agrupan las galaxias con el tiempo.<\/p>\n\n\n\n<p>DESI todav\u00eda est\u00e1 en las primeras etapas de su misi\u00f3n. El proyecto ha entrado en su cuarto a\u00f1o de recopilaci\u00f3n de datos, con planes de observar 40 millones de galaxias y cu\u00e1sares antes de que finalice. El trabajo ya supera lo que estudios anteriores lograron a lo largo de d\u00e9cadas.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.zmescience.com\/space\/desis-new-findings-confirm-einsteins-gravity-works-over-billions-of-light-years\/\">ZME Science<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Observatorio Nacional Kitt Peak, cerca de Tucson, Arizona, un telescopio observa el cosmos y registra la ubicaci\u00f3n de millones de galaxias. El telescopio de cuatro metros est\u00e1 cartografiando actualmente el universo para resolver uno de los mayores enigmas de la astrof\u00edsica: \u00bfpor qu\u00e9 el universo se expande m\u00e1s r\u00e1pido a medida que pasa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-64101","post","type-post","status-publish","format-standard","hentry","category-fisica"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/64101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=64101"}],"version-history":[{"count":9,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/64101\/revisions"}],"predecessor-version":[{"id":64112,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/64101\/revisions\/64112"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=64101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=64101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=64101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}