{"id":7711,"date":"2021-06-02T19:56:12","date_gmt":"2021-06-03T00:56:12","guid":{"rendered":"http:\/\/einsteresante.com\/?p=7711"},"modified":"2021-06-02T19:56:14","modified_gmt":"2021-06-03T00:56:14","slug":"este-nuevo-biomaterial-en-3d-puede-ayudar-a-revertir-la-artritis","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2021\/06\/02\/este-nuevo-biomaterial-en-3d-puede-ayudar-a-revertir-la-artritis\/","title":{"rendered":"Este nuevo biomaterial en 3D puede ayudar a revertir la artritis"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un andamio de biomaterial 3D que libera gradualmente c\u00e9lulas madre puede aliviar el dolor e incluso revertir la artritis. Hasta ahora s\u00f3lo se ha demostrado que funciona en las articulaciones de la rodilla de ratones, pero los investigadores son optimistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La osteoartritis afecta al 7% de la poblaci\u00f3n mundial, m\u00e1s de 500 millones de personas. En algunos pa\u00edses como EE. UU., la tasa es a\u00fan mayor, y la artritis afecta al 23% de todos los adultos (m\u00e1s de 54 millones de personas). Los principales s\u00edntomas de la artritis son dolor y rigidez en las articulaciones, que var\u00edan en intensidad (pero pueden empeorar con el tiempo).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No existen curas reales en el mercado para la afecci\u00f3n y los m\u00e9dicos generalmente se enfocan en aliviar el dolor. Pero la terapia con c\u00e9lulas madre ofrece una importante esperanza para finalmente hacer frente a la enfermedad. Sin embargo, encontrar la dosis correcta sigue siendo un problema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Demasiada dosis puede causar hinchaz\u00f3n y tejido cicatricial en el paciente; muy poco, y la terapia solo tiene \u00e9xito durante un per\u00edodo, y luego pueden reaparecer los problemas. Para superar este desaf\u00edo, los investigadores del Union Hospital de la Universidad de Ciencias de Huazhong sembraron c\u00e9lulas madre mesenquimales del cord\u00f3n umbilical en un tipo especial de biomaterial llamado criogel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las c\u00e9lulas madre mesenquimales han surgido como un tipo popular de c\u00e9lulas madre debido a su abundante suministro, al procedimiento de recolecci\u00f3n no invasivo y porque casi no plantean problemas \u00e9ticos. Mientras tanto, un criogel es una matriz de gel formada a temperaturas bajo cero. Los criogeles tienen poros interconectados como una esponja, y estos orificios permiten el transporte de peque\u00f1as part\u00edculas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El criogel ayuda a solucionar el problema de dosificaci\u00f3n porque asegura que las c\u00e9lulas madre implantadas permanezcan en la articulaci\u00f3n de la rodilla durante m\u00e1s tiempo, sin provocar riesgo de sobredosis. Cuando se aplic\u00f3 a ratones, los investigadores encontraron que el tratamiento fue eficaz para reducir el dolor de espalda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Se necesitan aproximadamente dos semanas para que la mitad de las c\u00e9lulas implantadas se vayan, pero sus efectos regenerativos se mantienen por m\u00e1s tiempo&#8221;, dijo el autor correspondiente Wei Tong del Departamento de Ortopedia del Union Hospital. &#8220;Por lo tanto, es posible que el resultado terap\u00e9utico se obtenga indirectamente, a trav\u00e9s de las c\u00e9lulas madre que secretan factores de crecimiento epid\u00e9rmico, que estimulan la proliferaci\u00f3n y curaci\u00f3n celular, en lugar de convertirse directamente en cart\u00edlago reci\u00e9n formado en la articulaci\u00f3n&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Todav\u00eda queda camino por recorrer<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.zmescience.com\/wp-content\/uploads\/2021\/06\/Osteoarthritis_and_rheumatoid_arthritis_-_Normal_joint_Osteoarthr_-_Smart-Servier-1024x576.jpg\" alt=\"\"\/><figcaption>Representaci\u00f3n de la osteoartritis y la artritis reumatoide, en comparaci\u00f3n con una articulaci\u00f3n sin inflamaci\u00f3n. Imagen a trav\u00e9s de Wiki Commons.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><br><\/strong>Es un avance emocionante y puede que comiencen los ensayos cl\u00ednicos en un futuro pr\u00f3ximo, pero por ahora, el estudio solo se ha demostrado en ratones. Los investigadores primero quieren probar la prueba de concepto en primates no humanos y luego pasar a los humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, si cree que puede estar sufriendo de artritis, siempre es recomendable buscar ayuda profesional, especialmente. Los hospitales o cl\u00ednicas, como las cl\u00ednicas de Everest Rehab, pueden ofrecer la experiencia y el asesoramiento que tanto se necesitan. Si bien no existe un tratamiento directo, una dieta saludable rica en frutas y verduras (y baja en carne y alimentos procesados) puede ayudar a reducir la inflamaci\u00f3n y el dolor. Otros alimentos como el pescado y las nueces tambi\u00e9n pueden ayudar a reducir la inflamaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los kilogramos adicionales tambi\u00e9n pueden causar problemas adicionales cuando se trata de artritis, ya que aumentan el peso de las rodillas. Las personas con sobrepeso tienen muchas m\u00e1s probabilidades de desarrollar osteoartritis que las que tienen un peso saludable. La dieta y el ejercicio pueden ayudarlo a mantener su peso en un rango saludable. Con el tiempo, tratamientos innovadores como el de Zhang y sus colegas pueden ayudar finalmente a revertir la artritis y facilitar la vida de millones de personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.zmescience.com\/science\/new-3d-bio-material-could-help-reverse-arthritis\/\">ZME Science<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un andamio de biomaterial 3D que libera gradualmente c\u00e9lulas madre puede aliviar el dolor e incluso revertir la artritis. Hasta ahora s\u00f3lo se ha demostrado que funciona en las articulaciones de la rodilla de ratones, pero los investigadores son optimistas. La osteoartritis afecta al 7% de la poblaci\u00f3n mundial, m\u00e1s de 500 millones de personas. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-7711","post","type-post","status-publish","format-standard","hentry","category-salud-y-medicina"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/7711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=7711"}],"version-history":[{"count":8,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/7711\/revisions"}],"predecessor-version":[{"id":7719,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/7711\/revisions\/7719"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=7711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=7711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=7711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}