{"id":97177,"date":"2026-04-14T17:13:09","date_gmt":"2026-04-14T22:13:09","guid":{"rendered":"https:\/\/einsteresante.com\/?p=97177"},"modified":"2026-04-14T17:13:10","modified_gmt":"2026-04-14T22:13:10","slug":"nuevo-lavado-de-frutas-elimina-los-pesticidas-y-prolonga-su-vida-util","status":"publish","type":"post","link":"https:\/\/einsteresante.com\/index.php\/2026\/04\/14\/nuevo-lavado-de-frutas-elimina-los-pesticidas-y-prolonga-su-vida-util\/","title":{"rendered":"Nuevo lavado de frutas elimina los pesticidas y prolonga su vida \u00fatil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Investigadores de la Universidad de Columbia Brit\u00e1nica han desarrollado un lavado natural y biodegradable que elimina hasta el 96% de los residuos de pesticidas de la fruta y ralentiza el oscurecimiento y la p\u00e9rdida de humedad. Esto podr\u00eda significar manzanas, uvas y otras frutas m\u00e1s seguras que, adem\u00e1s, se mantienen frescas y crujientes durante d\u00edas m\u00e1s. Con el aumento de los precios de los alimentos y el desperdicio de casi la mitad de los productos frescos en todo el mundo cada a\u00f1o, encontrar una manera de reducir la exposici\u00f3n a los pesticidas y disminuir el deterioro podr\u00eda tener un gran impacto. Los hallazgos se\u00a0<a href=\"https:\/\/pubs.acs.org\/doi\/10.1021\/acsnano.5c20410\" target=\"_blank\" rel=\"noreferrer noopener\">publican<\/a>\u00a0en\u00a0ACS Nano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nuestro objetivo era crear un m\u00e9todo de lavado sencillo, seguro y asequible que mejorara tanto la seguridad como la calidad de los alimentos&#8221;, declar\u00f3 la Dra. Tianxi Yang, autora principal y profesora adjunta de la Facultad de Sistemas Agrarios y Alimentarios de la UBC. &#8220;La gente no deber\u00eda tener que elegir entre comer productos frescos y preocuparse por lo que contienen&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Una forma segura y de origen vegetal de limpiar productos agr\u00edcolas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque los niveles de pesticidas en frutas y verduras est\u00e1n estrictamente regulados, a menudo quedan residuos. Para quienes consumen grandes cantidades de la misma fruta o verdura \u2014como los ni\u00f1os que devoran grandes tazones de bayas\u2014, la cantidad de residuos puede superar los l\u00edmites recomendados. Fue esta preocupaci\u00f3n, motivada por la afici\u00f3n del hijo de la Dra. Yang por los ar\u00e1ndanos frescos, lo que la impuls\u00f3 a buscar una mejor manera de limpiar la fruta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nuevo m\u00e9todo de lavado utiliza diminutas part\u00edculas de almid\u00f3n \u2014el mismo carbohidrato que se encuentra en el ma\u00edz y las patatas\u2014 recubiertas de hierro y \u00e1cido t\u00e1nico. El \u00e1cido t\u00e1nico es un compuesto vegetal que le da al t\u00e9 y al vino su sabor seco. Cuando el hierro y el \u00e1cido t\u00e1nico se unen, forman c\u00famulos pegajosos, similares a una esponja, que pueden atrapar los pesticidas y desprenderlos de la superficie de la fruta. El equipo prob\u00f3 el m\u00e9todo de lavado aplicando tres pesticidas de uso com\u00fan a las manzanas en concentraciones t\u00edpicas y reales de aproximadamente 10 miligramos por litro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En pruebas realizadas con manzanas, el lavado elimin\u00f3 entre el 86 % y el 96 % de estos pesticidas. Enjuagar con agua del grifo, bicarbonato de sodio o almid\u00f3n com\u00fan suele eliminar menos de la mitad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un recubrimiento que mantiene la fruta fresca por m\u00e1s tiempo.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tras lavar la fruta, se sumerge de nuevo en la soluci\u00f3n para formar una capa ligera,\u00a0<a href=\"https:\/\/phys.org\/news\/2025-01-sustainable-nanofiber-coating-fruit-shelf.html?utm_source=embeddings&amp;utm_medium=related&amp;utm_campaign=internal\">comestible y<\/a>\u00a0biodegradable. Las manzanas cortadas tratadas con este recubrimiento se oxidaron mucho m\u00e1s lentamente y perdieron menos agua durante dos d\u00edas en el frigor\u00edfico. Las uvas enteras se mantuvieron turgentes durante 15 d\u00edas a temperatura ambiente, en comparaci\u00f3n con el notable marchitamiento de las uvas sin tratar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El recubrimiento act\u00faa como una segunda piel transpirable. Los indicadores de calidad de los alimentos, como la acidez y los az\u00facares solubles, tambi\u00e9n se mantuvieron m\u00e1s elevados en la fruta recubierta&#8221;, afirm\u00f3 el Dr. Yang.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"385\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-55.png\" alt=\"\" class=\"wp-image-97208\" srcset=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-55.png 800w, https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-55-300x144.png 300w, https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-55-768x370.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">Imagen que muestra la captura en c\u00e1mara r\u00e1pida de uvas y manzanas sumergidas en el lavado de la UBC, las cuales se oscurecen y pierden menos humedad en comparaci\u00f3n con los controles. Cr\u00e9dito: Tianxi Yang\/Relaciones con los medios de la UBC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El recubrimiento tambi\u00e9n mostr\u00f3 efectos antimicrobianos, lo que significa que puede inhibir las bacterias da\u00f1inas. El estudio estim\u00f3 que lavar una manzana mediana en la soluci\u00f3n aportar\u00eda una cantidad segura de hierro, muy por debajo del l\u00edmite m\u00e1ximo diario para adultos establecido por las autoridades alimentarias norteamericanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;M\u00e1s all\u00e1 de la seguridad y la vida \u00fatil, nuestra f\u00f3rmula utiliza micronutrientes como el hierro y compuestos fen\u00f3licos que ofrecen beneficios adicionales para la salud&#8221;, afirm\u00f3 el Dr. Yang. &#8220;No solo reduce el riesgo, sino que tambi\u00e9n puede aportar valor nutricional&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Desde el procesamiento industrial hasta los fregaderos de cocina<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dado que los ingredientes son econ\u00f3micos y se mezclan con agua, los investigadores afirman que el m\u00e9todo de lavado podr\u00eda ampliarse f\u00e1cilmente para su uso industrial. El equipo trabaja actualmente en el perfeccionamiento, la ampliaci\u00f3n de la escala y las pruebas de la f\u00f3rmula para su uso en plantas procesadoras comerciales, donde la fruta se limpia antes de su env\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nuestras primeras estimaciones de costos sugieren que a\u00f1adir\u00eda aproximadamente tres centavos por manzana, un precio comparable al de los recubrimientos comerciales actuales, pero con el beneficio adicional de la eliminaci\u00f3n de pesticidas y la prolongaci\u00f3n de la vida \u00fatil&#8221;, dijo el Dr. Yang.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-56-1024x768.png\" alt=\"\" class=\"wp-image-97210\" srcset=\"https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-56-1024x768.png 1024w, https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-56-300x225.png 300w, https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-56-768x576.png 768w, https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-56-1536x1152.png 1536w, https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-56-2048x1536.png 2048w, https:\/\/einsteresante.com\/wp-content\/uploads\/2026\/04\/image-56-136x102.png 136w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">El nuevo producto de lavado de la UBC elimina los pesticidas y prolonga la vida \u00fatil de los productos. Cr\u00e9dito: Sachi Wickramasinghe\/Relaciones con los medios de la UBC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo tambi\u00e9n ve potencial para una versi\u00f3n dom\u00e9stica. &#8220;Imaginen un aerosol o una pastilla que se pueda a\u00f1adir al agua justo antes de lavar la fruta&#8221;, coment\u00f3 el Dr. Yang. El equipo se\u00f1ala que se necesitan m\u00e1s pruebas antes de su uso dom\u00e9stico, incluyendo la revisi\u00f3n regulatoria y estudios en condiciones reales con diferentes frutas y h\u00e1bitos de lavado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nuestra esperanza&#8221;, dijo el Dr. Yang, &#8220;es ayudar a la gente a sentirse segura de los productos que llevan a casa, sabiendo que son m\u00e1s seguros, duran m\u00e1s y generan menos residuos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/phys.org\/news\/2026-04-fruit-pesticides-shelf-life.html\">Phys.org<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Investigadores de la Universidad de Columbia Brit\u00e1nica han desarrollado un lavado natural y biodegradable que elimina hasta el 96% de los residuos de pesticidas de la fruta y ralentiza el oscurecimiento y la p\u00e9rdida de humedad. Esto podr\u00eda significar manzanas, uvas y otras frutas m\u00e1s seguras que, adem\u00e1s, se mantienen frescas y crujientes durante d\u00edas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":97212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-97177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-y-medicina"],"_links":{"self":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/97177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/comments?post=97177"}],"version-history":[{"count":4,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/97177\/revisions"}],"predecessor-version":[{"id":97213,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/posts\/97177\/revisions\/97213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media\/97212"}],"wp:attachment":[{"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/media?parent=97177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/categories?post=97177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/einsteresante.com\/index.php\/wp-json\/wp\/v2\/tags?post=97177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}